{"id":1411,"count":1,"description":"","link":"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/","name":"m\u00e4nner","slug":"maenner","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>m\u00e4nner Archives | zlcopenhagen.com<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"m\u00e4nner Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/\" \/>\n<meta property=\"og:site_name\" content=\"zlcopenhagen.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zlcopenhagen.com\/wp-content\/uploads\/2014\/11\/zlc-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1908\" \/>\n\t<meta property=\"og:image:height\" content=\"1062\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"m\u00e4nner Archives | zlcopenhagen.com","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"m\u00e4nner Archives","og_url":"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/","og_site_name":"zlcopenhagen.com","og_image":[{"width":1908,"height":1062,"url":"https:\/\/zlcopenhagen.com\/wp-content\/uploads\/2014\/11\/zlc-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/","url":"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/","name":"m\u00e4nner Archives | zlcopenhagen.com","isPartOf":{"@id":"https:\/\/zlcopenhagen.com\/#website"},"breadcrumb":{"@id":"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zlcopenhagen.com\/de\/"},{"@type":"ListItem","position":2,"name":"m\u00e4nner"}]},{"@type":"WebSite","@id":"https:\/\/zlcopenhagen.com\/#website","url":"https:\/\/zlcopenhagen.com\/","name":"zlcopenhagen.com","description":"","publisher":{"@id":"https:\/\/zlcopenhagen.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zlcopenhagen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/zlcopenhagen.com\/#organization","name":"ZLCOPENHAGEN","alternateName":"ZLCOPENHAGEN","url":"https:\/\/zlcopenhagen.com\/","logo":{"@id":"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/#local-main-organization-logo"},"image":{"@id":"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/#local-main-organization-logo"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCy7JINwB6DMr2fA9yHpDQJg"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zlcopenhagen.com\/de\/tag\/maenner\/#local-main-organization-logo","url":"https:\/\/zlcopenhagen.com\/wp-content\/uploads\/2016\/05\/blog-logo.jpg","contentUrl":"https:\/\/zlcopenhagen.com\/wp-content\/uploads\/2016\/05\/blog-logo.jpg","width":68,"height":68,"caption":"ZLCOPENHAGEN"}]}},"_links":{"self":[{"href":"https:\/\/zlcopenhagen.com\/de\/wp-json\/wp\/v2\/tags\/1411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zlcopenhagen.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/zlcopenhagen.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/zlcopenhagen.com\/de\/wp-json\/wp\/v2\/posts?tags=1411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}